{"id":47238,"date":"2019-01-17T13:58:34","date_gmt":"2019-01-17T12:58:34","guid":{"rendered":"https:\/\/spreitzer.de\/technique-de-mesure\/testeur-de-circularite-testeur-de-circularite\/"},"modified":"2026-07-08T07:51:59","modified_gmt":"2026-07-08T05:51:59","slug":"testeur-de-circularite-testeur-de-circularite","status":"publish","type":"page","link":"https:\/\/spreitzer.de\/fr\/technique-de-mesure\/testeur-de-circularite-testeur-de-circularite\/","title":{"rendered":"Testeur de circularit\u00e9 | Testeur de circularit\u00e9"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"47238\" class=\"elementor elementor-47238 elementor-12178\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4da51f9 e-con-full e-flex e-con e-parent\" data-id=\"4da51f9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2357caf ob-has-background-overlay elementor-widget elementor-widget-image\" data-id=\"2357caf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_photomorph_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"765\" src=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2021\/05\/Spreitzer-Spanntechnik-Messtechnik-Banner.jpg\" class=\"attachment-full size-full wp-image-50370\" alt=\"Spreitzer Rottweil : mesures et contr\u00f4les\" srcset=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2021\/05\/Spreitzer-Spanntechnik-Messtechnik-Banner.jpg 1920w, https:\/\/spreitzer.de\/wp-content\/uploads\/2021\/05\/Spreitzer-Spanntechnik-Messtechnik-Banner-300x120.jpg 300w, https:\/\/spreitzer.de\/wp-content\/uploads\/2021\/05\/Spreitzer-Spanntechnik-Messtechnik-Banner-1024x408.jpg 1024w, https:\/\/spreitzer.de\/wp-content\/uploads\/2021\/05\/Spreitzer-Spanntechnik-Messtechnik-Banner-768x306.jpg 768w, https:\/\/spreitzer.de\/wp-content\/uploads\/2021\/05\/Spreitzer-Spanntechnik-Messtechnik-Banner-1536x612.jpg 1536w, https:\/\/spreitzer.de\/wp-content\/uploads\/2021\/05\/Spreitzer-Spanntechnik-Messtechnik-Banner-200x80.jpg 200w, https:\/\/spreitzer.de\/wp-content\/uploads\/2021\/05\/Spreitzer-Spanntechnik-Messtechnik-Banner-400x159.jpg 400w, https:\/\/spreitzer.de\/wp-content\/uploads\/2021\/05\/Spreitzer-Spanntechnik-Messtechnik-Banner-600x239.jpg 600w, https:\/\/spreitzer.de\/wp-content\/uploads\/2021\/05\/Spreitzer-Spanntechnik-Messtechnik-Banner-800x319.jpg 800w, https:\/\/spreitzer.de\/wp-content\/uploads\/2021\/05\/Spreitzer-Spanntechnik-Messtechnik-Banner-1200x478.jpg 1200w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c0c9e1b e-flex e-con-boxed e-con e-parent\" data-id=\"c0c9e1b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b40e8a9 ob-has-background-overlay elementor-widget elementor-widget-image\" data-id=\"b40e8a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_photomorph_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2019\/12\/Icon-Messen-Messtechnik.png\" class=\"attachment-large size-large wp-image-49347\" alt=\"Spreitzer Rottweil Salons Technique de mesure Icon\" srcset=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2019\/12\/Icon-Messen-Messtechnik.png 100w, https:\/\/spreitzer.de\/wp-content\/uploads\/2019\/12\/Icon-Messen-Messtechnik-66x66.png 66w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8db578c elementor-absolute ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"8db578c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">7<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a50029a e-con-full e-flex e-con e-child\" data-id=\"a50029a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-f596460 e-con-full e-flex e-con e-child\" data-id=\"f596460\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9d00d98 ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"9d00d98\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">7<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49817cb ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"49817cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Testeur de circularit\u00e9 | Testeur de circularit\u00e9<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-79def32 e-con-full e-flex e-con e-child\" data-id=\"79def32\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-32b8a40 elementor-widget__width-initial elementor-widget-tablet_extra__width-initial ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"32b8a40\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_postman_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tMesure de la concentricit\u00e9, contr\u00f4le de la concentricit\u00e9 directement sur la machine. Nous proposons des appareils de contr\u00f4le de la concentricit\u00e9 sans pointes, des appareils de contr\u00f4le de la concentricit\u00e9 avec prismes d&rsquo;appui, des appareils de contr\u00f4le de la concentricit\u00e9 avec supports de roulement et des appareils de mesure de la concentricit\u00e9 avec contre-pointes. Le contr\u00f4le de concentricit\u00e9 peut \u00eatre effectu\u00e9 en moins de 10 secondes, sans connaissances pr\u00e9alables.  \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bd1ba1e e-con-full e-flex e-con e-child\" data-id=\"bd1ba1e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0926130 ob-has-background-overlay elementor-widget elementor-widget-button\" data-id=\"0926130\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_butterbutton_use_it&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/shop.spreitzer.de\/Pruefen\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M224 32l48 64H464h48v48V432v48H464 48 0V432 80 32H48 224zm48 112H248l-14.4-19.2L200 80H48V432H464V144H272zm64 128c0 17.8-4.9 34.5-13.3 48.9L361 359.2l17 17L344 410.1l-17-17-38.4-38.4C274.4 363.2 257.8 368 240 368c-53 0-96-43-96-96s43-96 96-96s96 43 96 96zm-96 48a48 48 0 1 0 0-96 48 48 0 1 0 0 96z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Trouver des produits de m\u00e9trologie adapt\u00e9s<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c668919 ob-has-background-overlay elementor-widget elementor-widget-button\" data-id=\"c668919\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_butterbutton_use_it&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/spreitzer.de\/pdf_de\/rundlaufpruefgeraete.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M288 32V0H224V32 274.7l-73.4-73.4L128 178.7 82.7 224l22.6 22.6 128 128L256 397.3l22.6-22.6 128-128L429.3 224 384 178.7l-22.6 22.6L288 274.7V32zM0 512H512V352H346.5l-45.3 45.3L256 442.5l-45.3-45.3L165.5 352H0V512zM432 408a24 24 0 1 1 0 48 24 24 0 1 1 0-48z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PDF Appareils de contr\u00f4le de la rotation<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-dce-background-image-url=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2019\/12\/Spreitzer-Spanntechnik-Bildgrafik-Counter.jpg\" class=\"elementor-element elementor-element-d5de232 e-flex e-con-boxed e-con e-parent\" data-id=\"d5de232\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;,&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f67e092 e-con-full e-flex e-con e-child\" data-id=\"f67e092\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ccb6ffb ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"ccb6ffb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Appareils de contr\u00f4le de concentricit\u00e9 | Appareils de mesure de concentricit\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f136b4c ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"f136b4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_postman_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>R\u00e9duisez jusqu&rsquo;\u00e0 80 % les temps de pr\u00e9paration et d&rsquo;arr\u00eat de votre machine d&rsquo;usinage co\u00fbteuse !<\/strong><br><br>\nLes appareils de contr\u00f4le de concentricit\u00e9 \u00e0 \u00e9carteurs offrent une grande flexibilit\u00e9, des temps de r\u00e9glage courts, une grande pr\u00e9cision de concentricit\u00e9 et conviennent \u00e0 diff\u00e9rentes g\u00e9om\u00e9tries.\n\nLes <strong>appareils de contr\u00f4le de concentricit\u00e9<\/strong> sont utilis\u00e9s pour contr\u00f4ler les surfaces ext\u00e9rieures, int\u00e9rieures et planes des pi\u00e8ces tournantes. La concentricit\u00e9 d\u2019un profil circulaire rev\u00eat une importance capitale pour la fabrication d\u2019arbres, de douilles, de roues dent\u00e9es ou de roulements. Exemples issus du secteur automobile : arbres \u00e0 cames, vilebrequins, arbres \u00e0 cardan, arbres de transmission.  \n\nNos appareils de mesure de concentricit\u00e9 permettent de d\u00e9terminer la concentricit\u00e9 de deux ou plusieurs diam\u00e8tres et d&rsquo;effectuer des mesures de faux-rond. Sur les mod\u00e8les RPG, RPG AL, RPG mini et RPG micro, la pi\u00e8ce est entra\u00een\u00e9e sans pointes entre trois rouleaux. On obtient ainsi une pr\u00e9cision de concentricit\u00e9 de 0,002 mm. La construction robuste, dot\u00e9e de roulements pr\u00e9contraints pour les rouleaux d&rsquo;appui, est con\u00e7ue pour garantir une longue dur\u00e9e de vie. Les diff\u00e9rentes versions disponibles permettent de couvrir une plage de diam\u00e8tres allant de 0,8 \u00e0 240 mm.    \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcf8eff ob-has-background-overlay elementor-widget elementor-widget-n-accordion\" data-id=\"bcf8eff\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]},&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1980\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1980\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Qu'est-ce que le test de circularit\u00e9 ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus-square\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M400 32H48C21.5 32 0 53.5 0 80v352c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V80c0-26.5-21.5-48-48-48zM92 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H92z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus-square\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M400 32H48C21.5 32 0 53.5 0 80v352c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V80c0-26.5-21.5-48-48-48zm-32 252c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92H92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1980\" class=\"elementor-element elementor-element-ef03798 e-con-full e-flex e-con e-child\" data-id=\"ef03798\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7712520 ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"7712520\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_postman_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le contr\u00f4le de concentricit\u00e9 est une m\u00e9thode de v\u00e9rification de la pr\u00e9cision des pi\u00e8ces de machines, en particulier des pi\u00e8ces rotatives telles que les axes, les broches d&rsquo;outils ou les dispositifs de serrage de pi\u00e8ces. Il s&rsquo;agit d&rsquo;une mesure de contr\u00f4le qualit\u00e9 importante dans le secteur du travail des m\u00e9taux et dans d&rsquo;autres industries o\u00f9 la pr\u00e9cision et l&rsquo;exactitude jouent un r\u00f4le important. <\/p><p>Le contr\u00f4le de circularit\u00e9 est effectu\u00e9 en serrant la pi\u00e8ce \u00e0 contr\u00f4ler dans le dispositif de serrage et en lui imprimant un mouvement de rotation. Pendant la rotation, la pi\u00e8ce est mesur\u00e9e \u00e0 l&rsquo;aide d&rsquo;un support de comparateur et d&rsquo;un comparateur \u00e0 cadran afin de d\u00e9terminer si la pi\u00e8ce tourne exactement rond et si elle pr\u00e9sente des variations de forme ou d&rsquo;orientation. <\/p><p>Diff\u00e9rents niveaux de contr\u00f4le peuvent \u00eatre requis en fonction de la tol\u00e9rance et de l&rsquo;utilisation pr\u00e9vue du composant. Le contr\u00f4le peut \u00eatre effectu\u00e9 manuellement ou de mani\u00e8re automatis\u00e9e, les machines CNC modernes \u00e9tant capables d&rsquo;effectuer le contr\u00f4le de concentricit\u00e9 automatiquement et de surveiller les r\u00e9sultats en temps r\u00e9el. <\/p><p>Le contr\u00f4le de concentricit\u00e9 est une m\u00e9thode importante pour garantir la qualit\u00e9 et la pr\u00e9cision des pi\u00e8ces de machine et joue un r\u00f4le essentiel dans la fabrication moderne. Il permet de d\u00e9tecter les d\u00e9fauts \u00e0 un stade pr\u00e9coce et d&rsquo;am\u00e9liorer l&rsquo;efficacit\u00e9 de la production en \u00e9vitant les rebuts et les r\u00e9p\u00e9titions inutiles. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9de4427 ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"9de4427\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Tol\u00e9rances de forme et de position | Possibilit\u00e9s de contr\u00f4le<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf0a070 ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"cf0a070\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_postman_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dans le domaine de la m\u00e9trologie, le contr\u00f4le de la concentricit\u00e9 occupe une place particuli\u00e8rement importante. Un montage de mesure appropri\u00e9 ainsi qu&rsquo;une pr\u00e9cision ad\u00e9quate de l&rsquo;appareil de mesure de la concentricit\u00e9 sont la base d&rsquo;une mesure pr\u00e9cise. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8525141 ob-has-background-overlay elementor-widget elementor-widget-image\" data-id=\"8525141\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_photomorph_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1500\" height=\"865\" src=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Pruefmoeglichkeiten-Rundlaufpruefgerate.png\" class=\"attachment-full size-full wp-image-47261\" alt=\"Possibilit\u00e9s de contr\u00f4le : appareils de contr\u00f4le de concentricit\u00e9\" srcset=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Pruefmoeglichkeiten-Rundlaufpruefgerate.png 1500w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Pruefmoeglichkeiten-Rundlaufpruefgerate-300x173.png 300w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Pruefmoeglichkeiten-Rundlaufpruefgerate-1024x591.png 1024w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Pruefmoeglichkeiten-Rundlaufpruefgerate-768x443.png 768w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Pruefmoeglichkeiten-Rundlaufpruefgerate-200x115.png 200w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Pruefmoeglichkeiten-Rundlaufpruefgerate-400x231.png 400w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Pruefmoeglichkeiten-Rundlaufpruefgerate-600x346.png 600w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Pruefmoeglichkeiten-Rundlaufpruefgerate-800x461.png 800w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Pruefmoeglichkeiten-Rundlaufpruefgerate-1200x692.png 1200w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93c0d4f ob-has-background-overlay elementor-widget elementor-widget-n-accordion\" data-id=\"93c0d4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]},&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1540\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1540\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\">   D\u00e9finitions Tol\u00e9rances de position <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus-square\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M400 32H48C21.5 32 0 53.5 0 80v352c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V80c0-26.5-21.5-48-48-48zM92 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H92z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus-square\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M400 32H48C21.5 32 0 53.5 0 80v352c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48V80c0-26.5-21.5-48-48-48zm-32 252c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92H92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1540\" class=\"elementor-element elementor-element-52859e0 e-con-full e-flex e-con e-child\" data-id=\"52859e0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-590aa75 ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"590aa75\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_postman_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Circularit\u00e9 : <\/strong>la ligne de circonf\u00e9rence doit \u00eatre perpendiculaire \u00e0 l&rsquo;axe central dans tous les plans de coupe, entre deux cercles concentriques.<\/p><p><strong>Perpendicularit\u00e9 : <\/strong>pour les surfaces : la surface doit \u00eatre situ\u00e9e entre deux plans perpendiculaires \u00e0 la r\u00e9f\u00e9rence.<\/p><p>pour les axes : l&rsquo;axe du cylindre doit \u00eatre situ\u00e9 dans un cylindre perpendiculaire \u00e0 la surface de r\u00e9f\u00e9rence.<\/p><p><strong>Rotation de la pi\u00e8ce : <\/strong>La r\u00e9gularit\u00e9 d&rsquo;une pi\u00e8ce \u00e0 usiner ronde en rotation. Pour une rotation autour de l&rsquo;axe de r\u00e9f\u00e9rence, la concentricit\u00e9 ne doit pas d\u00e9passer une valeur pr\u00e9d\u00e9finie. <\/p><p><strong>Rotation totale, rotation et plan\u00e9it\u00e9 : <\/strong>En cas de rotations multiples autour de l&rsquo;axe de r\u00e9f\u00e9rence et de d\u00e9placement axial ou radial simultan\u00e9, l&rsquo;\u00e9cart de concentricit\u00e9 ou de plan\u00e9it\u00e9 ne doit pas d\u00e9passer une valeur pr\u00e9d\u00e9finie.<\/p><p><strong>Concentricit\u00e9 et coaxialit\u00e9 : <\/strong>Le centre du cercle tol\u00e9r\u00e9 doit \u00eatre situ\u00e9 dans un cercle dont le centre est concentrique \u00e0 la r\u00e9f\u00e9rence.<sup id=\"cite_ref-:1_5-0\" class=\"reference\"><\/sup><\/p><p>L&rsquo;axe de la surface tol\u00e9ranc\u00e9e doit \u00eatre situ\u00e9 dans un cylindre dont l&rsquo;axe central est coaxial \u00e0 la r\u00e9f\u00e9rence.<\/p><p><strong>\u00e9cart de coaxialit\u00e9 et de concentricit\u00e9.  <\/strong>Ecarts qui se rapportent \u00e0 un axe de r\u00e9f\u00e9rence. C&rsquo;est autour de cet axe que tourne la pi\u00e8ce lorsque l&rsquo;\u00e9l\u00e9ment tol\u00e9ranc\u00e9 est mesur\u00e9. Les \u00e9carts de concentricit\u00e9 sont dus \u00e0 un d\u00e9calage d&rsquo;axe, \u00e0 un manque de coaxialit\u00e9 ou \u00e0 des \u00e9carts de circularit\u00e9.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ef44ae6 e-con-full e-flex e-con e-child\" data-id=\"ef44ae6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e56240 ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"6e56240\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Appareils de contr\u00f4le de concentricit\u00e9, sans pointes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a3541f e-con-full e-flex e-con e-child\" data-id=\"5a3541f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-01d9a90 elementor-widget__width-initial elementor-widget-mobile__width-initial ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"01d9a90\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_postman_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAppareils de contr\u00f4le de concentricit\u00e9 sans centre destin\u00e9s aux mesures et contr\u00f4les sur les surfaces ext\u00e9rieures, int\u00e9rieures et planes. Adapt\u00e9s aux contr\u00f4les unitaires et en s\u00e9rie, pour une mesure unilat\u00e9rale. Mesures bilat\u00e9rales possibles \u00e0 l&rsquo;aide d&rsquo;accessoires.  \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-76ca7b6 e-con-full e-flex e-con e-child\" data-id=\"76ca7b6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-baf01b6 ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"baf01b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Principe de mesure des appareils de contr\u00f4le de la circularit\u00e9 sans pointe<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a2809c ob-has-background-overlay elementor-widget elementor-widget-image\" data-id=\"3a2809c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_photomorph_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1700\" height=\"420\" src=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzinp-spitzenlose-Rundlaufpruefgeraete-1.png\" class=\"attachment-full size-full wp-image-50856\" alt=\"Principe de mesure des appareils de contr\u00f4le de la circularit\u00e9 sans pointe\" srcset=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzinp-spitzenlose-Rundlaufpruefgeraete-1.png 1700w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzinp-spitzenlose-Rundlaufpruefgeraete-1-300x74.png 300w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzinp-spitzenlose-Rundlaufpruefgeraete-1-1024x253.png 1024w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzinp-spitzenlose-Rundlaufpruefgeraete-1-768x190.png 768w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzinp-spitzenlose-Rundlaufpruefgeraete-1-1536x379.png 1536w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzinp-spitzenlose-Rundlaufpruefgeraete-1-200x49.png 200w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzinp-spitzenlose-Rundlaufpruefgeraete-1-400x99.png 400w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzinp-spitzenlose-Rundlaufpruefgeraete-1-600x148.png 600w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzinp-spitzenlose-Rundlaufpruefgeraete-1-800x198.png 800w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzinp-spitzenlose-Rundlaufpruefgeraete-1-1200x296.png 1200w\" sizes=\"(max-width: 1700px) 100vw, 1700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d50e2cd e-grid e-con-full e-con e-child\" data-id=\"d50e2cd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-5dd6075 e-con-full e-flex e-con e-child\" data-id=\"5dd6075\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6acc2bc elementor-align-justify ob-has-background-overlay elementor-widget elementor-widget-button\" data-id=\"6acc2bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/shop.spreitzer.de\/Rundlaufpruefgeraete-RPG-micro\/B701700001\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Testeur de circularit\u00e9 RPG micro<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b328c9 ob-has-background-overlay elementor-widget elementor-widget-image\" data-id=\"7b328c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_photomorph_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-micro.png\" class=\"attachment-large size-large wp-image-47259\" alt=\"Testeur de circularit\u00e9 RPG micro\" srcset=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-micro.png 600w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-micro-300x300.png 300w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-micro-150x150.png 150w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-micro-400x400.png 400w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-micro-66x66.png 66w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-micro-200x200.png 200w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c996ef e-con-full e-flex e-con e-child\" data-id=\"6c996ef\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ca9415b elementor-align-justify ob-has-background-overlay elementor-widget elementor-widget-button\" data-id=\"ca9415b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/shop.spreitzer.de\/Rundlaufpruefgeraete-RPG-mini\/B701200007M\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Testeur de circularit\u00e9 RPG mini<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff4d8ab ob-has-background-overlay elementor-widget elementor-widget-image\" data-id=\"ff4d8ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_photomorph_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-mini.jpg\" class=\"attachment-large size-large wp-image-47249\" alt=\"Testeur de circularit\u00e9 RPG mini\" srcset=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-mini.jpg 600w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-mini-300x300.jpg 300w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-mini-150x150.jpg 150w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-mini-400x400.jpg 400w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-mini-66x66.jpg 66w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-mini-200x200.jpg 200w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-66f99ca e-con-full e-flex e-con e-child\" data-id=\"66f99ca\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0fe1a72 elementor-align-justify ob-has-background-overlay elementor-widget elementor-widget-button\" data-id=\"0fe1a72\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/shop.spreitzer.de\/Rundlaufpruefgeraete-RPG-AL\/B701000001M\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Appareil de contr\u00f4le de la concentricit\u00e9 RPG AL<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78f79e2 ob-has-background-overlay elementor-widget elementor-widget-image\" data-id=\"78f79e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_photomorph_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-AL.png\" class=\"attachment-large size-large wp-image-50859\" alt=\"Appareil de contr\u00f4le de la concentricit\u00e9 RPG AL\" srcset=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-AL.png 600w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-AL-300x300.png 300w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-AL-150x150.png 150w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-AL-400x400.png 400w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-AL-66x66.png 66w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-AL-200x200.png 200w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6472c25 e-con-full e-flex e-con e-child\" data-id=\"6472c25\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-161e220 elementor-align-justify ob-has-background-overlay elementor-widget elementor-widget-button\" data-id=\"161e220\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/shop.spreitzer.de\/Rundlaufpruefgeraet-RPG-35100\/B700500005\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Appareil de contr\u00f4le de rotation RPG 35100<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb06c51 ob-has-background-overlay elementor-widget elementor-widget-image\" data-id=\"fb06c51\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_photomorph_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG.png\" class=\"attachment-large size-large wp-image-50862\" alt=\"Appareil de contr\u00f4le de concentricit\u00e9 RPG\" srcset=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG.png 600w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-300x300.png 300w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-150x150.png 150w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-400x400.png 400w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-66x66.png 66w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPG-200x200.png 200w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ca0b52 elementor-align-right ob-has-background-overlay elementor-widget elementor-widget-button\" data-id=\"3ca0b52\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_butterbutton_use_it&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/shop.spreitzer.de\/Pruefen\/Rundlaufpruefgeraete-spitzenlos\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M224 32l48 64H464h48v48V432v48H464 48 0V432 80 32H48 224zm48 112H248l-14.4-19.2L200 80H48V432H464V144H272zm64 128c0 17.8-4.9 34.5-13.3 48.9L361 359.2l17 17L344 410.1l-17-17-38.4-38.4C274.4 363.2 257.8 368 240 368c-53 0-96-43-96-96s43-96 96-96s96 43 96 96zm-96 48a48 48 0 1 0 0-96 48 48 0 1 0 0 96z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Appareils de test de circularit\u00e9 sans pointe<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5719adc e-con-full e-flex e-con e-child\" data-id=\"5719adc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7413815 ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"7413815\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Appareils de contr\u00f4le de concentricit\u00e9 \u00e9quip\u00e9s de supports de roulement<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-52da8ee e-con-full e-flex e-con e-child\" data-id=\"52da8ee\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-868c937 e-grid e-con-full e-con e-child\" data-id=\"868c937\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-bd5e665 e-con-full e-flex e-con e-child\" data-id=\"bd5e665\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-489292e elementor-align-justify ob-has-background-overlay elementor-widget elementor-widget-button\" data-id=\"489292e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/shop.spreitzer.de\/Rundlaufpruefgeraet-RPGR-mit-Abrollboecken\/B703000002M\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Appareil de contr\u00f4le de rotation RPGR avec supports de d\u00e9roulement<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2cd533b ob-has-background-overlay elementor-widget elementor-widget-image\" data-id=\"2cd533b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_photomorph_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPGR.png\" class=\"attachment-large size-large wp-image-47252\" alt=\"Appareil de contr\u00f4le de concentricit\u00e9 RPGR\" srcset=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPGR.png 600w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPGR-300x300.png 300w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPGR-150x150.png 150w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPGR-400x400.png 400w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPGR-66x66.png 66w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPGR-200x200.png 200w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1ac770d e-con-full e-flex e-con e-child\" data-id=\"1ac770d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0ecde46 ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"0ecde46\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Principe de mesure des appareils de contr\u00f4le de la circularit\u00e9 sans pointe<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97f2430 ob-has-background-overlay elementor-widget elementor-widget-image\" data-id=\"97f2430\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_photomorph_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1700\" height=\"420\" src=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Abrollboecken.png\" class=\"attachment-full size-full wp-image-47251\" alt=\"Principe de mesure des appareils de contr\u00f4le de concentricit\u00e9 \u00e9quip\u00e9s de supports de roulement\" srcset=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Abrollboecken.png 1700w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Abrollboecken-300x74.png 300w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Abrollboecken-1024x253.png 1024w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Abrollboecken-768x190.png 768w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Abrollboecken-1536x379.png 1536w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Abrollboecken-200x49.png 200w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Abrollboecken-400x99.png 400w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Abrollboecken-600x148.png 600w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Abrollboecken-800x198.png 800w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Abrollboecken-1200x296.png 1200w\" sizes=\"(max-width: 1700px) 100vw, 1700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cac0a6a ob-has-background-overlay elementor-widget elementor-widget-button\" data-id=\"cac0a6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_butterbutton_use_it&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/shop.spreitzer.de\/Pruefen\/Rundlaufpruefgeraete-mit-Abrollboecken\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M224 32l48 64H464h48v48V432v48H464 48 0V432 80 32H48 224zm48 112H248l-14.4-19.2L200 80H48V432H464V144H272zm64 128c0 17.8-4.9 34.5-13.3 48.9L361 359.2l17 17L344 410.1l-17-17-38.4-38.4C274.4 363.2 257.8 368 240 368c-53 0-96-43-96-96s43-96 96-96s96 43 96 96zm-96 48a48 48 0 1 0 0-96 48 48 0 1 0 0 96z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Appareil de contr\u00f4le de rotation RPGR avec supports de d\u00e9roulement<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6657404 e-con-full e-flex e-con e-child\" data-id=\"6657404\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23b5c2e ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"23b5c2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Appareils de contr\u00f4le de concentricit\u00e9 \u00e9quip\u00e9s de prismes d'appui<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b484a1e e-con-full e-flex e-con e-child\" data-id=\"b484a1e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3884d0c e-grid e-con-full e-con e-child\" data-id=\"3884d0c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-a77f080 e-con-full e-flex e-con e-child\" data-id=\"a77f080\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f5933cd elementor-align-justify ob-has-background-overlay elementor-widget elementor-widget-button\" data-id=\"f5933cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/shop.spreitzer.de\/Rundlaufpruefgeraet-RPGP-mit-Auflageprismen\/B703000004M\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Appareil de contr\u00f4le de rotation RPGP avec prismes d'appui<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dcab4d1 ob-has-background-overlay elementor-widget elementor-widget-image\" data-id=\"dcab4d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_photomorph_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPGP.png\" class=\"attachment-large size-large wp-image-47254\" alt=\"Appareil de contr\u00f4le de concentricit\u00e9 RPGP\" srcset=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPGP.png 600w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPGP-300x300.png 300w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPGP-150x150.png 150w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPGP-400x400.png 400w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPGP-66x66.png 66w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPGP-200x200.png 200w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-088e7a8 e-con-full e-flex e-con e-child\" data-id=\"088e7a8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bcf7ae9 ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"bcf7ae9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Principe de mesure Syst\u00e8mes d'inspection rotatifs avec prismes d'appui<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f6baa5 ob-has-background-overlay elementor-widget elementor-widget-image\" data-id=\"9f6baa5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_photomorph_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1700\" height=\"420\" src=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Auflageprisma.png\" class=\"attachment-full size-full wp-image-47253\" alt=\"Principe de mesure Syst\u00e8mes d&apos;inspection rotatifs avec prismes d&apos;appui\" srcset=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Auflageprisma.png 1700w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Auflageprisma-300x74.png 300w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Auflageprisma-1024x253.png 1024w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Auflageprisma-768x190.png 768w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Auflageprisma-1536x379.png 1536w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Auflageprisma-200x49.png 200w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Auflageprisma-400x99.png 400w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Auflageprisma-600x148.png 600w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Auflageprisma-800x198.png 800w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Auflageprisma-1200x296.png 1200w\" sizes=\"(max-width: 1700px) 100vw, 1700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9adff57 ob-has-background-overlay elementor-widget elementor-widget-button\" data-id=\"9adff57\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_butterbutton_use_it&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/shop.spreitzer.de\/Pruefen\/Rundlaufpruefgeraete-mit-Auflageprismen\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M224 32l48 64H464h48v48V432v48H464 48 0V432 80 32H48 224zm48 112H248l-14.4-19.2L200 80H48V432H464V144H272zm64 128c0 17.8-4.9 34.5-13.3 48.9L361 359.2l17 17L344 410.1l-17-17-38.4-38.4C274.4 363.2 257.8 368 240 368c-53 0-96-43-96-96s43-96 96-96s96 43 96 96zm-96 48a48 48 0 1 0 0-96 48 48 0 1 0 0 96z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Appareil de contr\u00f4le de rotation RPGR avec prismes d'appui<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b7f53f3 e-con-full e-flex e-con e-child\" data-id=\"b7f53f3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f74fb9 ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"2f74fb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Appareils de contr\u00f4le de concentricit\u00e9 \u00e9quip\u00e9s de contre-pointes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-02818dd e-con-full e-flex e-con e-child\" data-id=\"02818dd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-8eba86f e-grid e-con-full e-con e-child\" data-id=\"8eba86f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-691814a e-con-full e-flex e-con e-child\" data-id=\"691814a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c69bf24 elementor-align-justify ob-has-background-overlay elementor-widget elementor-widget-button\" data-id=\"c69bf24\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/shop.spreitzer.de\/Rundlaufpruefgeraet-RPGS-mit-Reitstoecken\/B702000001M\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Appareil de contr\u00f4le de la concentricit\u00e9 RPGS avec contre-pointes<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4d572d ob-has-background-overlay elementor-widget elementor-widget-image\" data-id=\"c4d572d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_photomorph_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPGS.png\" class=\"attachment-large size-large wp-image-47256\" alt=\"Appareil de contr\u00f4le de concentricit\u00e9 RPGS\" srcset=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPGS.png 600w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPGS-300x300.png 300w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPGS-150x150.png 150w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPGS-400x400.png 400w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPGS-66x66.png 66w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Rundlaufpruefgeraet-RPGS-200x200.png 200w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-29675cd e-con-full e-flex e-con e-child\" data-id=\"29675cd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d115797 ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"d115797\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Principe de mesure des appareils d'essai de circularit\u00e9 avec contre-pointes<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55713d5 ob-has-background-overlay elementor-widget elementor-widget-image\" data-id=\"55713d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_photomorph_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1700\" height=\"420\" src=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Reitstoecken.png\" class=\"attachment-full size-full wp-image-47255\" alt=\"Principe de mesure des appareils de contr\u00f4le de concentricit\u00e9 \u00e0 tiges de mesure\" srcset=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Reitstoecken.png 1700w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Reitstoecken-300x74.png 300w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Reitstoecken-1024x253.png 1024w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Reitstoecken-768x190.png 768w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Reitstoecken-1536x379.png 1536w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Reitstoecken-200x49.png 200w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Reitstoecken-400x99.png 400w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Reitstoecken-600x148.png 600w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Reitstoecken-800x198.png 800w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Rundlaufpruefgeraete-mit-Reitstoecken-1200x296.png 1200w\" sizes=\"(max-width: 1700px) 100vw, 1700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89f40a1 ob-has-background-overlay elementor-widget elementor-widget-button\" data-id=\"89f40a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_butterbutton_use_it&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/shop.spreitzer.de\/Pruefen\/Rundlaufpruefgeraete-mit-Reitstoecken\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M224 32l48 64H464h48v48V432v48H464 48 0V432 80 32H48 224zm48 112H248l-14.4-19.2L200 80H48V432H464V144H272zm64 128c0 17.8-4.9 34.5-13.3 48.9L361 359.2l17 17L344 410.1l-17-17-38.4-38.4C274.4 363.2 257.8 368 240 368c-53 0-96-43-96-96s43-96 96-96s96 43 96 96zm-96 48a48 48 0 1 0 0-96 48 48 0 1 0 0 96z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Appareil de contr\u00f4le de concentricit\u00e9 RPGR avec contre-pointes<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-110358b e-con-full e-flex e-con e-child\" data-id=\"110358b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c2c13de ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"c2c13de\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unit\u00e9s rotatives de pr\u00e9cision<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cdc5363 e-con-full e-flex e-con e-child\" data-id=\"cdc5363\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-86338b4 e-grid e-con-full e-con e-child\" data-id=\"86338b4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-226701f e-con-full e-flex e-con e-child\" data-id=\"226701f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d31ffae elementor-align-justify ob-has-background-overlay elementor-widget elementor-widget-button\" data-id=\"d31ffae\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/shop.spreitzer.de\/Praezisions-Dreheinheit-PDE\/B705000004M\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Unit\u00e9 rotative de pr\u00e9cision PDE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60e2ef2 ob-has-background-overlay elementor-widget elementor-widget-image\" data-id=\"60e2ef2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_photomorph_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2023\/04\/Praezisions-Dreheinheit-PDE-140-DBF-140VA-Platte.png\" class=\"attachment-large size-large wp-image-51549\" alt=\"Unit\u00e9 de tournage de pr\u00e9cision PDE sur plaque\" srcset=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2023\/04\/Praezisions-Dreheinheit-PDE-140-DBF-140VA-Platte.png 600w, https:\/\/spreitzer.de\/wp-content\/uploads\/2023\/04\/Praezisions-Dreheinheit-PDE-140-DBF-140VA-Platte-300x300.png 300w, https:\/\/spreitzer.de\/wp-content\/uploads\/2023\/04\/Praezisions-Dreheinheit-PDE-140-DBF-140VA-Platte-150x150.png 150w, https:\/\/spreitzer.de\/wp-content\/uploads\/2023\/04\/Praezisions-Dreheinheit-PDE-140-DBF-140VA-Platte-400x400.png 400w, https:\/\/spreitzer.de\/wp-content\/uploads\/2023\/04\/Praezisions-Dreheinheit-PDE-140-DBF-140VA-Platte-66x66.png 66w, https:\/\/spreitzer.de\/wp-content\/uploads\/2023\/04\/Praezisions-Dreheinheit-PDE-140-DBF-140VA-Platte-200x200.png 200w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-25dce5b e-con-full e-flex e-con e-child\" data-id=\"25dce5b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78c64ad ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"78c64ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Principe de mesure Unit\u00e9s rotatives de pr\u00e9cision<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50827e1 ob-has-background-overlay elementor-widget elementor-widget-image\" data-id=\"50827e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_photomorph_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1700\" height=\"420\" src=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Praezisionsdreheinheit-1.png\" class=\"attachment-full size-full wp-image-47258\" alt=\"Principe de mesure Unit\u00e9s rotatives de pr\u00e9cision\" srcset=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Praezisionsdreheinheit-1.png 1700w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Praezisionsdreheinheit-1-300x74.png 300w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Praezisionsdreheinheit-1-1024x253.png 1024w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Praezisionsdreheinheit-1-768x190.png 768w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Praezisionsdreheinheit-1-1536x379.png 1536w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Praezisionsdreheinheit-1-200x49.png 200w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Praezisionsdreheinheit-1-400x99.png 400w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Praezisionsdreheinheit-1-600x148.png 600w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Praezisionsdreheinheit-1-800x198.png 800w, https:\/\/spreitzer.de\/wp-content\/uploads\/2022\/07\/Messprinzip-Praezisionsdreheinheit-1-1200x296.png 1200w\" sizes=\"(max-width: 1700px) 100vw, 1700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c43aee ob-has-background-overlay elementor-widget elementor-widget-button\" data-id=\"5c43aee\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_butterbutton_use_it&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/shop.spreitzer.de\/Pruefen\/Praezisions-Dreheinheiten\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M224 32l48 64H464h48v48V432v48H464 48 0V432 80 32H48 224zm48 112H248l-14.4-19.2L200 80H48V432H464V144H272zm64 128c0 17.8-4.9 34.5-13.3 48.9L361 359.2l17 17L344 410.1l-17-17-38.4-38.4C274.4 363.2 257.8 368 240 368c-53 0-96-43-96-96s43-96 96-96s96 43 96 96zm-96 48a48 48 0 1 0 0-96 48 48 0 1 0 0 96z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Unit\u00e9 rotative de pr\u00e9cision pde<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a82fc7 e-con-full e-flex e-con e-child\" data-id=\"5a82fc7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-1989317 e-con-full e-flex e-con e-child\" data-id=\"1989317\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4a65fb5 ob-has-background-overlay elementor-widget elementor-widget-image\" data-id=\"4a65fb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_photomorph_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"230\" src=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2021\/08\/spreitzer-messtechnik-rundlaufpruefgeraet-uhr.jpg\" class=\"attachment-full size-full wp-image-47247\" alt=\"Un chronom\u00e8tre qui tourne\" srcset=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2021\/08\/spreitzer-messtechnik-rundlaufpruefgeraet-uhr.jpg 250w, https:\/\/spreitzer.de\/wp-content\/uploads\/2021\/08\/spreitzer-messtechnik-rundlaufpruefgeraet-uhr-200x184.jpg 200w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ea52cb7 e-con-full e-flex e-con e-child\" data-id=\"ea52cb7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ff1b1de ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"ff1b1de\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3 conseils pratiques pour votre succ\u00e8s<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a884b02 ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"a884b02\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_postman_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Contr\u00f4le pr\u00e9cis de la concentricit\u00e9. En moins de 10 secondes. Sans aucune connaissance pr\u00e9alable. Directement sur la machine.   <\/b><\/p><ol><li>R\u00e9duisez consid\u00e9rablement vos co\u00fbts d&rsquo;erreurs internes et externes !<\/li><li>R\u00e9duisez jusqu&rsquo;\u00e0 80% les temps de r\u00e9glage et d&rsquo;arr\u00eat de votre co\u00fbteuse machine CNC !<\/li><li>Efficace gr\u00e2ce \u00e0 sa simplicit\u00e9 d&rsquo;utilisation. Indispensable ! <\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e94e711 e-con-full e-flex e-con e-parent\" data-id=\"e94e711\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fa446d9 elementor-cta--layout-image-left elementor-cta--valign-middle elementor-cta--mobile-layout-image-above elementor-cta--mobile_extra-layout-image-left elementor-cta--skin-classic elementor-animated-content ob-has-background-overlay elementor-widget elementor-widget-global elementor-global-46494 elementor-global-35436 elementor-widget-call-to-action\" data-id=\"fa446d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/spreitzer.de\/wp-content\/uploads\/2026\/05\/Spreitzer-Spanntechnik-Loesungen-Spanntechnik-Kontakt.jpg);\" role=\"img\" aria-label=\"Spreitzer-Spanntechnik-Rottweil-Loesungen-Spanntechnik-Kontakt\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2019\/12\/Icon-Telefonhoerer.png\" class=\"attachment-thumbnail size-thumbnail wp-image-49383\" alt=\"Ic\u00f4ne repr\u00e9sentant un combin\u00e9 t\u00e9l\u00e9phonique de Spreitzer Rottweil\" srcset=\"https:\/\/spreitzer.de\/wp-content\/uploads\/2019\/12\/Icon-Telefonhoerer.png 100w, https:\/\/spreitzer.de\/wp-content\/uploads\/2019\/12\/Icon-Telefonhoerer-66x66.png 66w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tQue pouvons-nous faire pour vous ?\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tR\u00e9duisez vos co\u00fbts de fabrication. Des t\u00e2ches de mesure r\u00e9solues avec pr\u00e9cision en quelques secondes. \t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"https:\/\/spreitzer.de\/kontakt\/\">\n\t\t\t\t\t\tContact\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>7 7 Testeur de circularit\u00e9 | Testeur de circularit\u00e9 Mesure de la concentricit\u00e9, contr\u00f4le de la concentricit\u00e9 directement sur la machine. Nous proposons des appareils de contr\u00f4le de la concentricit\u00e9 sans pointes, des appareils de contr\u00f4le de la concentricit\u00e9 avec prismes d&rsquo;appui, des appareils de contr\u00f4le de la concentricit\u00e9 avec supports de roulement et des [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"parent":47192,"menu_order":301,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-47238","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/spreitzer.de\/fr\/wp-json\/wp\/v2\/pages\/47238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spreitzer.de\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/spreitzer.de\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/spreitzer.de\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/spreitzer.de\/fr\/wp-json\/wp\/v2\/comments?post=47238"}],"version-history":[{"count":3,"href":"https:\/\/spreitzer.de\/fr\/wp-json\/wp\/v2\/pages\/47238\/revisions"}],"predecessor-version":[{"id":62477,"href":"https:\/\/spreitzer.de\/fr\/wp-json\/wp\/v2\/pages\/47238\/revisions\/62477"}],"up":[{"embeddable":true,"href":"https:\/\/spreitzer.de\/fr\/wp-json\/wp\/v2\/pages\/47192"}],"wp:attachment":[{"href":"https:\/\/spreitzer.de\/fr\/wp-json\/wp\/v2\/media?parent=47238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}